{"id":7508,"date":"2022-08-17T11:56:56","date_gmt":"2022-08-17T18:56:56","guid":{"rendered":"https:\/\/www.midvalleystem.org\/es\/cart\/"},"modified":"2022-08-17T11:56:56","modified_gmt":"2022-08-17T18:56:56","slug":"cart","status":"publish","type":"page","link":"https:\/\/www.midvalleystem.org\/es\/cart\/","title":{"rendered":"Cart"},"content":{"rendered":"\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-7508","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cart - Mid-Valley STEM-CTE Hub - Espa\u00f1ol<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.midvalleystem.org\/es\/cart\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cart - Mid-Valley STEM-CTE Hub - Espa\u00f1ol\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.midvalleystem.org\/es\/cart\/\" \/>\n<meta property=\"og:site_name\" content=\"Mid-Valley STEM-CTE Hub - Espa\u00f1ol\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.midvalleystem.org\\\/es\\\/cart\\\/\",\"url\":\"https:\\\/\\\/www.midvalleystem.org\\\/es\\\/cart\\\/\",\"name\":\"Cart - Mid-Valley STEM-CTE Hub - Espa\u00f1ol\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.midvalleystem.org\\\/es\\\/#website\"},\"datePublished\":\"2022-08-17T18:56:56+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.midvalleystem.org\\\/es\\\/cart\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.midvalleystem.org\\\/es\\\/cart\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.midvalleystem.org\\\/es\\\/cart\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.midvalleystem.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cart\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.midvalleystem.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.midvalleystem.org\\\/es\\\/\",\"name\":\"Mid-Valley STEM-CTE Hub - Espa\u00f1ol\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.midvalleystem.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cart - Mid-Valley STEM-CTE Hub - Espa\u00f1ol","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.midvalleystem.org\/es\/cart\/","og_locale":"en_US","og_type":"article","og_title":"Cart - Mid-Valley STEM-CTE Hub - Espa\u00f1ol","og_url":"https:\/\/www.midvalleystem.org\/es\/cart\/","og_site_name":"Mid-Valley STEM-CTE Hub - Espa\u00f1ol","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.midvalleystem.org\/es\/cart\/","url":"https:\/\/www.midvalleystem.org\/es\/cart\/","name":"Cart - Mid-Valley STEM-CTE Hub - Espa\u00f1ol","isPartOf":{"@id":"https:\/\/www.midvalleystem.org\/es\/#website"},"datePublished":"2022-08-17T18:56:56+00:00","breadcrumb":{"@id":"https:\/\/www.midvalleystem.org\/es\/cart\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.midvalleystem.org\/es\/cart\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.midvalleystem.org\/es\/cart\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.midvalleystem.org\/es\/"},{"@type":"ListItem","position":2,"name":"Cart"}]},{"@type":"WebSite","@id":"https:\/\/www.midvalleystem.org\/es\/#website","url":"https:\/\/www.midvalleystem.org\/es\/","name":"Mid-Valley STEM-CTE Hub - Espa\u00f1ol","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.midvalleystem.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.midvalleystem.org\/es\/wp-json\/wp\/v2\/pages\/7508","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.midvalleystem.org\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.midvalleystem.org\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.midvalleystem.org\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.midvalleystem.org\/es\/wp-json\/wp\/v2\/comments?post=7508"}],"version-history":[{"count":0,"href":"https:\/\/www.midvalleystem.org\/es\/wp-json\/wp\/v2\/pages\/7508\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.midvalleystem.org\/es\/wp-json\/wp\/v2\/media?parent=7508"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}