{"id":4031,"date":"2021-01-14T23:47:28","date_gmt":"2021-01-15T07:47:28","guid":{"rendered":"http:\/\/www.midvalleystem.org\/?p=4031"},"modified":"2022-09-15T14:00:36","modified_gmt":"2022-09-15T21:00:36","slug":"diviertete-con-la-exploracion-de-carreras","status":"publish","type":"post","link":"https:\/\/www.midvalleystem.org\/es\/2021\/01\/14\/diviertete-con-la-exploracion-de-carreras\/","title":{"rendered":"\u00a1Divi\u00e9rtete con la Exploraci\u00f3n de Carreras!"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">\u00a1La publicaci\u00f3n <\/span><a href=\"http:\/\/www.midvalleystem.org\/category\/stemctefridays\/\"><b>#STEMCTEFridays<\/b><\/a><span style=\"font-weight: 400;\"> de esta semana tiene que ver con la exploraci\u00f3n de carreras!<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u00bfQu\u00e9 tan joven es demasiado joven para empezar a pensar en carreras? Para nosotros en Mid-Valley STEM-CTE Hub, nunca se puede ser demasiado joven para comenzar la exploraci\u00f3n de carreras. Creemos que la exploraci\u00f3n de carreras es una parte cr\u00edtica de la educaci\u00f3n y el desarrollo de cada ni\u00f1o\/a. Como el \u00fanico STEM Hub en Oregon con CTE (Educaci\u00f3n T\u00e9cnica y Profesional) en nuestro nombre, creemos firmemente en el aprendizaje relacionado con la carrera. Una de nuestras prioridades es desarrollar oportunidades STEM y CTE para los estudiantes para que puedan ayudar a construir la fuerza laboral y la prosperidad econ\u00f3mica de nuestra regi\u00f3n.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><b>Maneras de ayudar a sus hijos con la exploraci\u00f3n de carreras<\/b><\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Lea sobre diferentes carreras: Puede encontrar informaci\u00f3n en l\u00ednea sobre todas las carreras imaginables. Cuando su hijo\/a exprese inter\u00e9s en cualquier ocupaci\u00f3n, an\u00edmelo a investigar para aprender m\u00e1s.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Hable con personas en diferentes ocupaciones: Pregunte a las personas sobre sus trabajos cuando los vea ocupados en un trabajo con el que ambos no est\u00e1n familiarizados. Averig\u00fce qu\u00e9 formaci\u00f3n necesitaban y si les gusta lo que hacen.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Use sus contactos: Cuando su hijo\/a exprese inter\u00e9s en aprender sobre una carrera en particular, acceda a su red profesional para encontrar a alguien que pueda hablar con \u00e9l o ella al respecto.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Ayude a su hijo a conocerse a s\u00ed mismo: Cuando su hijo\/a ingrese a la escuela secundaria, debe realizar una autoevaluaci\u00f3n para descubrir sus intereses, valores, personalidad y aptitudes.<\/span><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><b>Actividades y recursos para una mayor exploraci\u00f3n<\/b><\/p>\n<p><b>Estudiantes de K\u00ednder a 5\u00b0 grado: Una variedad de actividades y recursos para que los estudiantes m\u00e1s peque\u00f1os participen en la exploraci\u00f3n de carreras.<\/b><\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><a href=\"http:\/\/www.mychildsfuture.com\/item.htm?edlvl=1\"><b>My Children\u2019s Future (El futuro de mis hijos):<\/b><\/a><span style=\"font-weight: 400;\"> Explore esta p\u00e1gina para obtener una visi\u00f3n m\u00e1s detallada del proceso de desarrollo profesional y los pasos que son importantes para su hijo\/a en edad de primaria.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><a href=\"http:\/\/www.mychildsfuture.com\/item.htm?id=82&amp;edlvl=1\"><b>Actividades para estudiantes de primaria:<\/b><\/a><span style=\"font-weight: 400;\"> Consulte esta p\u00e1gina de actividades de \u201cMy Children\u2019s Future\u201d.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><a href=\"http:\/\/breitlinks.com\/careers\/career_pdfs\/familytreews.pdf\"><b>Career Family Tree<\/b><\/a><span style=\"font-weight: 400;\"> (\u00c1rbol geneal\u00f3gico de carreras): Eche un vistazo a las carreras elegidas por sus abuelos, padres, t\u00edas, t\u00edos y otros parientes.<\/span><\/li>\n<\/ul>\n<p><b>Estudiantes de escuela secundaria: M\u00e1s recursos y actividades de exploraci\u00f3n profesional en profundidad para involucrar a los estudiantes de escuela secundaria.<\/b><\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><a href=\"http:\/\/www.mychildsfuture.com\/item.htm?edlvl=2\"><b>My Children\u2019s Future (El futuro de mis hijos):<\/b><\/a><span style=\"font-weight: 400;\"> Explore esta p\u00e1gina para obtener una visi\u00f3n m\u00e1s detallada del proceso de desarrollo profesional y los pasos que son importantes para su hijo\/a en edad de escuela secundaria.<\/span><\/li>\n<\/ul>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><a href=\"http:\/\/www.mychildsfuture.com\/item.htm?id=83&amp;edlvl=2\"><b>Actividades para estudiantes de secundaria<\/b><\/a><span style=\"font-weight: 400;\">: Consulte esta p\u00e1gina de actividades de \u201cMy Children\u2019s Future\u201d.<\/span><\/li>\n<\/ul>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><a href=\"https:\/\/www.bls.gov\/k12\/students\/careers\/career-exploration.htm\"><b>Exploraci\u00f3n de carreras de la Oficina de Trabajo y Estad\u00edsticas:<\/b><\/a><span style=\"font-weight: 400;\"> este recurso desglosa diferentes categor\u00edas de inter\u00e9s basadas en carreras.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><a href=\"https:\/\/www.mynextmove.org\/explore\/ip\"><b>Perfil de intereses de O*Net:<\/b><\/a><span style=\"font-weight: 400;\"> El Perfil de intereses de O*NET puede ayudarlos a descubrir cu\u00e1les son sus intereses y qu\u00e9 tipo de carreras le gustar\u00eda explorar.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><a href=\"https:\/\/www.mynextmove.org\/find\/interests\"><b>Mi pr\u00f3ximo paso:<\/b><\/a><span style=\"font-weight: 400;\"> Explore carreras ordenadas por inter\u00e9s. Sus intereses pueden ayudarlos a encontrar carreras que le gustar\u00eda explorar. Cuanto m\u00e1s satisfaga una carrera sus intereses, m\u00e1s probable ser\u00e1 que sea satisfactoria y gratificante para usted.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><a href=\"https:\/\/www.truity.com\/test\/holland-code-career-test\"><b>Prueba de evaluaci\u00f3n de carrera del C\u00f3digo de Holanda<\/b><\/a><span style=\"font-weight: 400;\">:\u00a0Esta es la evaluaci\u00f3n de carrera que damos a los estudiantes cuando hacemos presentaciones en las escuelas.<\/span><\/li>\n<\/ul>\n<p><b>Estudiantes de preparatoria: Actividades y recursos para estudiantes de preparatoria que permiten una exploraci\u00f3n profunda de carreras y opciones postsecundarias.<\/b><\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><a href=\"https:\/\/www.bls.gov\/k12\/home.htm\"><b>Oficina de Estad\u00edsticas y Trabajo:<\/b><\/a><span style=\"font-weight: 400;\"> Vea informaci\u00f3n sobre cientos de trabajos en su <\/span><a href=\"https:\/\/www.bls.gov\/ooh\"><b>Manual de Perspectivas Ocupacionales<\/b><\/a><span style=\"font-weight: 400;\"> completo. Obtenga la aplicaci\u00f3n CareerInfo para el manual (disponible para dispositivos <\/span><a href=\"https:\/\/apps.apple.com\/us\/app\/careerinfo\/id1476300397\"><b>iOS<\/b><\/a><span style=\"font-weight: 400;\"> y <\/span><a href=\"https:\/\/play.google.com\/store\/apps\/details?id=gov.dol.ooh_occupational_handbook&amp;hl=en_US\"><b>Android<\/b><\/a><span style=\"font-weight: 400;\">).\u00a0<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><a href=\"https:\/\/www.bls.gov\/k12\/students\/careers\/stem-table.htm\"><b>Tabla peri\u00f3dica interactiva de carreras STEM:<\/b><\/a><span style=\"font-weight: 400;\"> En lugar de elementos, BLS ha utilizado ocupaciones de Ciencia, Tecnolog\u00eda, Ingenier\u00eda y Matem\u00e1ticas (STEM). Pase el cursor sobre un &#8220;elemento&#8221; o grupo para resaltar esa disciplina. Descargue una versi\u00f3n en <\/span><a href=\"https:\/\/www.bls.gov\/k12\/teachers\/posters\/pdf\/periodic-table.pdf\"><b>PDF<\/b><\/a><span style=\"font-weight: 400;\"> de la tabla.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><a href=\"https:\/\/www.mynextmove.org\/explore\/ip\"><b>Perfil de intereses de O*Net:<\/b><\/a><span style=\"font-weight: 400;\"> El Perfil de intereses de O*NET puede ayudarlo a descubrir cu\u00e1les son sus intereses y qu\u00e9 tipo de carreras le gustar\u00eda explorar.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><a href=\"https:\/\/www.mynextmove.org\/find\/interests\"><b>Mi pr\u00f3ximo paso:<\/b><\/a><span style=\"font-weight: 400;\"> Explore carreras ordenadas por inter\u00e9s. Sus intereses pueden ayudarlos a encontrar carreras que le gustar\u00eda explorar. Cuanto m\u00e1s satisfaga una carrera sus intereses, m\u00e1s probable ser\u00e1 que sea satisfactoria y gratificante para usted.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><a href=\"https:\/\/www.truity.com\/test\/holland-code-career-test\"><b>Prueba de evaluaci\u00f3n de carrera del C\u00f3digo de Holanda<\/b><\/a><span style=\"font-weight: 400;\">:\u00a0Esta es la evaluaci\u00f3n de carrera que damos a los estudiantes cuando hacemos presentaciones en las escuelas.\u00a0<\/span><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400;\">Tambi\u00e9n somos un gran recurso para la exploraci\u00f3n de carreras:<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><a href=\"http:\/\/www.midvalleystem.org\/trades-notebook\/\"><b>Catalogo para Ocupaciones de Oficios Calificados en el Valle de Willamette<\/b><\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"\u00a1La publicaci\u00f3n #STEMCTEFridays de esta semana tiene que ver con la exploraci\u00f3n de carreras! \u00bfQu\u00e9 tan joven es demasiado joven para empezar a pensar en carreras? Para nosotros en Mid-Valley [&hellip;]","protected":false},"author":3,"featured_media":4035,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[25],"tags":[18,102,101,21,100,17],"class_list":["post-4031","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-stemctefridays","tag-career","tag-career-and-technical-education","tag-career-connected-learning","tag-cte","tag-exploration","tag-mid-valley-stem-cte-hub"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00a1Divi\u00e9rtete con la Exploraci\u00f3n de Carreras! - Mid-Valley STEM-CTE Hub - Espa\u00f1ol<\/title>\n<meta name=\"description\" content=\"\u00a1Divi\u00e9rtete con la Exploraci\u00f3n de Carreras!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.midvalleystem.org\/es\/2021\/01\/14\/diviertete-con-la-exploracion-de-carreras\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00a1Divi\u00e9rtete con la Exploraci\u00f3n de Carreras! - Mid-Valley STEM-CTE Hub - Espa\u00f1ol\" \/>\n<meta property=\"og:description\" content=\"\u00a1Divi\u00e9rtete con la Exploraci\u00f3n de Carreras!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.midvalleystem.org\/es\/2021\/01\/14\/diviertete-con-la-exploracion-de-carreras\/\" \/>\n<meta property=\"og:site_name\" content=\"Mid-Valley STEM-CTE Hub - Espa\u00f1ol\" \/>\n<meta property=\"article:published_time\" content=\"2021-01-15T07:47:28+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-09-15T21:00:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.midvalleystem.org\/media\/sites\/2\/2021\/01\/STEMCTEFriday_CareerExploration.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"940\" \/>\n\t<meta property=\"og:image:height\" content=\"788\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.midvalleystem.org\\\/es\\\/2021\\\/01\\\/14\\\/diviertete-con-la-exploracion-de-carreras\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.midvalleystem.org\\\/es\\\/2021\\\/01\\\/14\\\/diviertete-con-la-exploracion-de-carreras\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"\u00a1Divi\u00e9rtete con la Exploraci\u00f3n de Carreras!\",\"datePublished\":\"2021-01-15T07:47:28+00:00\",\"dateModified\":\"2022-09-15T21:00:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.midvalleystem.org\\\/es\\\/2021\\\/01\\\/14\\\/diviertete-con-la-exploracion-de-carreras\\\/\"},\"wordCount\":841,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.midvalleystem.org\\\/es\\\/2021\\\/01\\\/14\\\/diviertete-con-la-exploracion-de-carreras\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.midvalleystem.org\\\/media\\\/sites\\\/2\\\/2021\\\/01\\\/STEMCTEFriday_CareerExploration.jpg\",\"keywords\":[\"career\",\"career and technical education\",\"career-connected learning\",\"CTE\",\"exploration\",\"Mid-Valley STEM-CTE Hub\"],\"articleSection\":[\"#STEMCTEFridays\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.midvalleystem.org\\\/es\\\/2021\\\/01\\\/14\\\/diviertete-con-la-exploracion-de-carreras\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.midvalleystem.org\\\/es\\\/2021\\\/01\\\/14\\\/diviertete-con-la-exploracion-de-carreras\\\/\",\"url\":\"https:\\\/\\\/www.midvalleystem.org\\\/es\\\/2021\\\/01\\\/14\\\/diviertete-con-la-exploracion-de-carreras\\\/\",\"name\":\"\u00a1Divi\u00e9rtete con la Exploraci\u00f3n de Carreras! - Mid-Valley STEM-CTE Hub - Espa\u00f1ol\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.midvalleystem.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.midvalleystem.org\\\/es\\\/2021\\\/01\\\/14\\\/diviertete-con-la-exploracion-de-carreras\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.midvalleystem.org\\\/es\\\/2021\\\/01\\\/14\\\/diviertete-con-la-exploracion-de-carreras\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.midvalleystem.org\\\/media\\\/sites\\\/2\\\/2021\\\/01\\\/STEMCTEFriday_CareerExploration.jpg\",\"datePublished\":\"2021-01-15T07:47:28+00:00\",\"dateModified\":\"2022-09-15T21:00:36+00:00\",\"author\":{\"@id\":\"\"},\"description\":\"\u00a1Divi\u00e9rtete con la Exploraci\u00f3n de Carreras!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.midvalleystem.org\\\/es\\\/2021\\\/01\\\/14\\\/diviertete-con-la-exploracion-de-carreras\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.midvalleystem.org\\\/es\\\/2021\\\/01\\\/14\\\/diviertete-con-la-exploracion-de-carreras\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.midvalleystem.org\\\/es\\\/2021\\\/01\\\/14\\\/diviertete-con-la-exploracion-de-carreras\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.midvalleystem.org\\\/media\\\/sites\\\/2\\\/2021\\\/01\\\/STEMCTEFriday_CareerExploration.jpg\",\"contentUrl\":\"https:\\\/\\\/www.midvalleystem.org\\\/media\\\/sites\\\/2\\\/2021\\\/01\\\/STEMCTEFriday_CareerExploration.jpg\",\"width\":940,\"height\":788,\"caption\":\"STEMCTE Fridays: Career Exploration\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.midvalleystem.org\\\/es\\\/2021\\\/01\\\/14\\\/diviertete-con-la-exploracion-de-carreras\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.midvalleystem.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00a1Divi\u00e9rtete con la Exploraci\u00f3n de Carreras!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.midvalleystem.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.midvalleystem.org\\\/es\\\/\",\"name\":\"Mid-Valley STEM-CTE Hub - Espa\u00f1ol\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.midvalleystem.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"\",\"url\":\"https:\\\/\\\/www.midvalleystem.org\\\/es\\\/author\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00a1Divi\u00e9rtete con la Exploraci\u00f3n de Carreras! - Mid-Valley STEM-CTE Hub - Espa\u00f1ol","description":"\u00a1Divi\u00e9rtete con la Exploraci\u00f3n de Carreras!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.midvalleystem.org\/es\/2021\/01\/14\/diviertete-con-la-exploracion-de-carreras\/","og_locale":"en_US","og_type":"article","og_title":"\u00a1Divi\u00e9rtete con la Exploraci\u00f3n de Carreras! - Mid-Valley STEM-CTE Hub - Espa\u00f1ol","og_description":"\u00a1Divi\u00e9rtete con la Exploraci\u00f3n de Carreras!","og_url":"https:\/\/www.midvalleystem.org\/es\/2021\/01\/14\/diviertete-con-la-exploracion-de-carreras\/","og_site_name":"Mid-Valley STEM-CTE Hub - Espa\u00f1ol","article_published_time":"2021-01-15T07:47:28+00:00","article_modified_time":"2022-09-15T21:00:36+00:00","og_image":[{"width":940,"height":788,"url":"https:\/\/www.midvalleystem.org\/media\/sites\/2\/2021\/01\/STEMCTEFriday_CareerExploration.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Written by":"","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.midvalleystem.org\/es\/2021\/01\/14\/diviertete-con-la-exploracion-de-carreras\/#article","isPartOf":{"@id":"https:\/\/www.midvalleystem.org\/es\/2021\/01\/14\/diviertete-con-la-exploracion-de-carreras\/"},"author":{"name":"","@id":""},"headline":"\u00a1Divi\u00e9rtete con la Exploraci\u00f3n de Carreras!","datePublished":"2021-01-15T07:47:28+00:00","dateModified":"2022-09-15T21:00:36+00:00","mainEntityOfPage":{"@id":"https:\/\/www.midvalleystem.org\/es\/2021\/01\/14\/diviertete-con-la-exploracion-de-carreras\/"},"wordCount":841,"commentCount":0,"image":{"@id":"https:\/\/www.midvalleystem.org\/es\/2021\/01\/14\/diviertete-con-la-exploracion-de-carreras\/#primaryimage"},"thumbnailUrl":"https:\/\/www.midvalleystem.org\/media\/sites\/2\/2021\/01\/STEMCTEFriday_CareerExploration.jpg","keywords":["career","career and technical education","career-connected learning","CTE","exploration","Mid-Valley STEM-CTE Hub"],"articleSection":["#STEMCTEFridays"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.midvalleystem.org\/es\/2021\/01\/14\/diviertete-con-la-exploracion-de-carreras\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.midvalleystem.org\/es\/2021\/01\/14\/diviertete-con-la-exploracion-de-carreras\/","url":"https:\/\/www.midvalleystem.org\/es\/2021\/01\/14\/diviertete-con-la-exploracion-de-carreras\/","name":"\u00a1Divi\u00e9rtete con la Exploraci\u00f3n de Carreras! - Mid-Valley STEM-CTE Hub - Espa\u00f1ol","isPartOf":{"@id":"https:\/\/www.midvalleystem.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.midvalleystem.org\/es\/2021\/01\/14\/diviertete-con-la-exploracion-de-carreras\/#primaryimage"},"image":{"@id":"https:\/\/www.midvalleystem.org\/es\/2021\/01\/14\/diviertete-con-la-exploracion-de-carreras\/#primaryimage"},"thumbnailUrl":"https:\/\/www.midvalleystem.org\/media\/sites\/2\/2021\/01\/STEMCTEFriday_CareerExploration.jpg","datePublished":"2021-01-15T07:47:28+00:00","dateModified":"2022-09-15T21:00:36+00:00","author":{"@id":""},"description":"\u00a1Divi\u00e9rtete con la Exploraci\u00f3n de Carreras!","breadcrumb":{"@id":"https:\/\/www.midvalleystem.org\/es\/2021\/01\/14\/diviertete-con-la-exploracion-de-carreras\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.midvalleystem.org\/es\/2021\/01\/14\/diviertete-con-la-exploracion-de-carreras\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.midvalleystem.org\/es\/2021\/01\/14\/diviertete-con-la-exploracion-de-carreras\/#primaryimage","url":"https:\/\/www.midvalleystem.org\/media\/sites\/2\/2021\/01\/STEMCTEFriday_CareerExploration.jpg","contentUrl":"https:\/\/www.midvalleystem.org\/media\/sites\/2\/2021\/01\/STEMCTEFriday_CareerExploration.jpg","width":940,"height":788,"caption":"STEMCTE Fridays: Career Exploration"},{"@type":"BreadcrumbList","@id":"https:\/\/www.midvalleystem.org\/es\/2021\/01\/14\/diviertete-con-la-exploracion-de-carreras\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.midvalleystem.org\/es\/"},{"@type":"ListItem","position":2,"name":"\u00a1Divi\u00e9rtete con la Exploraci\u00f3n de Carreras!"}]},{"@type":"WebSite","@id":"https:\/\/www.midvalleystem.org\/es\/#website","url":"https:\/\/www.midvalleystem.org\/es\/","name":"Mid-Valley STEM-CTE Hub - Espa\u00f1ol","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.midvalleystem.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"","url":"https:\/\/www.midvalleystem.org\/es\/author\/"}]}},"jetpack_featured_media_url":"https:\/\/www.midvalleystem.org\/media\/sites\/2\/2021\/01\/STEMCTEFriday_CareerExploration.jpg","_links":{"self":[{"href":"https:\/\/www.midvalleystem.org\/es\/wp-json\/wp\/v2\/posts\/4031","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.midvalleystem.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.midvalleystem.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.midvalleystem.org\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.midvalleystem.org\/es\/wp-json\/wp\/v2\/comments?post=4031"}],"version-history":[{"count":1,"href":"https:\/\/www.midvalleystem.org\/es\/wp-json\/wp\/v2\/posts\/4031\/revisions"}],"predecessor-version":[{"id":7573,"href":"https:\/\/www.midvalleystem.org\/es\/wp-json\/wp\/v2\/posts\/4031\/revisions\/7573"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.midvalleystem.org\/es\/wp-json\/wp\/v2\/media\/4035"}],"wp:attachment":[{"href":"https:\/\/www.midvalleystem.org\/es\/wp-json\/wp\/v2\/media?parent=4031"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.midvalleystem.org\/es\/wp-json\/wp\/v2\/categories?post=4031"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.midvalleystem.org\/es\/wp-json\/wp\/v2\/tags?post=4031"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}