{"id":407,"count":1,"description":"","link":"https:\/\/www.midvalleystem.org\/es\/tag\/mechanic\/","name":"mechanic","slug":"mechanic","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>mechanic Archives - Mid-Valley STEM-CTE Hub - Espa\u00f1ol<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.midvalleystem.org\/es\/tag\/mechanic\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"mechanic Archives - Mid-Valley STEM-CTE Hub - Espa\u00f1ol\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.midvalleystem.org\/es\/tag\/mechanic\/\" \/>\n<meta property=\"og:site_name\" content=\"Mid-Valley STEM-CTE Hub - Espa\u00f1ol\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.midvalleystem.org\\\/es\\\/tag\\\/mechanic\\\/\",\"url\":\"https:\\\/\\\/www.midvalleystem.org\\\/es\\\/tag\\\/mechanic\\\/\",\"name\":\"mechanic Archives - Mid-Valley STEM-CTE Hub - Espa\u00f1ol\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.midvalleystem.org\\\/es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.midvalleystem.org\\\/es\\\/tag\\\/mechanic\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.midvalleystem.org\\\/es\\\/tag\\\/mechanic\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.midvalleystem.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"mechanic\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.midvalleystem.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.midvalleystem.org\\\/es\\\/\",\"name\":\"Mid-Valley STEM-CTE Hub - Espa\u00f1ol\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.midvalleystem.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"mechanic Archives - Mid-Valley STEM-CTE Hub - Espa\u00f1ol","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.midvalleystem.org\/es\/tag\/mechanic\/","og_locale":"en_US","og_type":"article","og_title":"mechanic Archives - Mid-Valley STEM-CTE Hub - Espa\u00f1ol","og_url":"https:\/\/www.midvalleystem.org\/es\/tag\/mechanic\/","og_site_name":"Mid-Valley STEM-CTE Hub - Espa\u00f1ol","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.midvalleystem.org\/es\/tag\/mechanic\/","url":"https:\/\/www.midvalleystem.org\/es\/tag\/mechanic\/","name":"mechanic Archives - Mid-Valley STEM-CTE Hub - Espa\u00f1ol","isPartOf":{"@id":"https:\/\/www.midvalleystem.org\/es\/#website"},"breadcrumb":{"@id":"https:\/\/www.midvalleystem.org\/es\/tag\/mechanic\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.midvalleystem.org\/es\/tag\/mechanic\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.midvalleystem.org\/es\/"},{"@type":"ListItem","position":2,"name":"mechanic"}]},{"@type":"WebSite","@id":"https:\/\/www.midvalleystem.org\/es\/#website","url":"https:\/\/www.midvalleystem.org\/es\/","name":"Mid-Valley STEM-CTE Hub - Espa\u00f1ol","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.midvalleystem.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.midvalleystem.org\/es\/wp-json\/wp\/v2\/tags\/407","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.midvalleystem.org\/es\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.midvalleystem.org\/es\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.midvalleystem.org\/es\/wp-json\/wp\/v2\/posts?tags=407"},{"href":"https:\/\/www.midvalleystem.org\/es\/wp-json\/wp\/v2\/tribe_events?tags=407"},{"href":"https:\/\/www.midvalleystem.org\/es\/wp-json\/wp\/v2\/tec_calendar_embed?tags=407"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}